{"id":280,"date":"2026-07-18T20:43:44","date_gmt":"2026-07-18T18:43:44","guid":{"rendered":"https:\/\/www.birresdorf.de\/blog\/?p=280"},"modified":"2026-07-18T20:43:44","modified_gmt":"2026-07-18T18:43:44","slug":"sportwoche-des-birresdorfer-sc-acht-tage-lang-fussball","status":"publish","type":"post","link":"https:\/\/www.birresdorf.de\/blog\/2026\/07\/18\/sportwoche-des-birresdorfer-sc-acht-tage-lang-fussball\/","title":{"rendered":"Sportwoche des Birresdorfer SC: Acht Tage lang Fu\u00dfball"},"content":{"rendered":"\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a97bc0c886c8&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a97bc0c886c8\" class=\"wp-block-image alignright size-medium wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.birresdorf.de\/blog\/wp-content\/uploads\/2026\/07\/2026-Sportwoche-Programm-v2-200x300.jpg\" alt=\"\" class=\"wp-image-281\" srcset=\"https:\/\/www.birresdorf.de\/blog\/wp-content\/uploads\/2026\/07\/2026-Sportwoche-Programm-v2-200x300.jpg 200w, https:\/\/www.birresdorf.de\/blog\/wp-content\/uploads\/2026\/07\/2026-Sportwoche-Programm-v2-683x1024.jpg 683w, https:\/\/www.birresdorf.de\/blog\/wp-content\/uploads\/2026\/07\/2026-Sportwoche-Programm-v2-768x1152.jpg 768w, https:\/\/www.birresdorf.de\/blog\/wp-content\/uploads\/2026\/07\/2026-Sportwoche-Programm-v2.jpg 1024w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ab dem kommenden Sonntag, 26. Juli 2026, hei\u00dft es wieder acht Tage Fu\u00dfball pur auf der Sportanlage Leimersdorf. Der Birresdorfer SC l\u00e4dt zu seiner traditionellen Sportwoche ein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am Sonntag geht es um 11:00 Uhr mit dem Reiterhof Sieburg Cup los. Vier Mannschaften k\u00e4mpfen um den begehrten Titel \u201eDorfmeister 2026\u201c. Ab 13:00 Uhr startet der Haribo Cup mit Seniorenmannschaften aus den Kreisligen B und C. Bis zum Abend treten sechs Mannschaften in zwei Gruppen gegeneinander an. Am darauffolgenden Mittwoch finden dann ab 18:30 Uhr die Finalpartien statt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abgerundet wird der erste Tag der Sportwoche durch ein ausgiebiges Kinderprogramm. Von 13:00 bis 15:00 Uhr besucht Clown Lefti das Sportgel\u00e4nde und Kinderschminken wird mit Nathalie Kratz angeboten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am Montag- und Dienstagabend finden ab 18:30 Uhr die Gruppenspiele des Baum Automobile Cups statt. Wiederum sechs Seniorenteams, diesmal aus A-Klasse und Bezirksliga, werden alles geben, um am Donnerstag zur gleichen Uhrzeit die Finalpartien zu bestreiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das zweite Wochenende wird am Freitag durch den 15. Yurita Cup eingel\u00e4utet. 13 Alt-Herren-Mannschaften messen sich auf Kleinfeld ab 18:00 Uhr in drei Gruppen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weitere H\u00f6hepunkte folgen am Samstag, den 01. August. Um 12:00 Uhr startet der Tag mit \u201eWalking Football\u201c ehe die dritte Auflage des Sch\u00fcttler Cups f\u00fcr Dorfmannschaften ausgetragen wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der kr\u00f6nende Abschluss ist dann am Sonntag, den 02. August. Ab 10:30 Uhr startet zun\u00e4chst der Elek-Fink-Cup f\u00fcr \u00dc50- und \u00dc60-Mannschaften.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um 12:30 Uhr findet ein Einlagespiel der ehemaligen A-Jugend Jahrg\u00e4nge 1986\/87 gegen die Grafschafter SG 2 statt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Abschlussspiel der Sportwoche stellt die Partie der Grafschafter SG gegen die SG Liebshausen im Rahmen der ersten Runde des Rheinlandpokals dar. Anpfiff ist um 15:00 Uhr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Birresdorfer Sportclub l\u00e4dt alle herzlich ein, die Sportwoche 2026 in Leimersdorf zu besuchen und gemeinsam eine Woche voller Sport, Gemeinschaft und guter Unterhaltung zu erleben. F\u00fcr das leibliche Wohl wird selbstverst\u00e4ndlich bestens gesorgt sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weitere Informationen beim Birresdorfer Sportclub: <a href=\"https:\/\/www.birresdorfer-sportclub.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.birresdorfer-sportclub.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ab dem kommenden Sonntag, 26. Juli 2026, hei\u00dft es wieder acht Tage Fu\u00dfball pur auf der Sportanlage Leimersdorf. Der Birresdorfer SC l\u00e4dt zu seiner traditionellen Sportwoche ein. Am Sonntag geht [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-280","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.birresdorf.de\/blog\/wp-json\/wp\/v2\/posts\/280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.birresdorf.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.birresdorf.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.birresdorf.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.birresdorf.de\/blog\/wp-json\/wp\/v2\/comments?post=280"}],"version-history":[{"count":1,"href":"https:\/\/www.birresdorf.de\/blog\/wp-json\/wp\/v2\/posts\/280\/revisions"}],"predecessor-version":[{"id":282,"href":"https:\/\/www.birresdorf.de\/blog\/wp-json\/wp\/v2\/posts\/280\/revisions\/282"}],"wp:attachment":[{"href":"https:\/\/www.birresdorf.de\/blog\/wp-json\/wp\/v2\/media?parent=280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.birresdorf.de\/blog\/wp-json\/wp\/v2\/categories?post=280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.birresdorf.de\/blog\/wp-json\/wp\/v2\/tags?post=280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}